{"id":24339,"date":"2024-12-06T06:18:48","date_gmt":"2024-12-06T06:18:48","guid":{"rendered":"https:\/\/www.anifuzion.com\/?page_id=24339"},"modified":"2025-05-29T04:15:46","modified_gmt":"2025-05-29T04:15:46","slug":"character-families","status":"publish","type":"page","link":"https:\/\/www.anifuzion.com\/id\/characters\/","title":{"rendered":"Character Families"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"24339\" class=\"elementor elementor-24339\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-58e0ab1 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"58e0ab1\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;,&quot;shape_divider_bottom&quot;:&quot;triangle&quot;}\">\n\t\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M500,98.9L0,6.1V0h1000v6.1L500,98.9z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-49c8b19b\" data-id=\"49c8b19b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-540634dd elementor-widget elementor-widget-heading\" data-id=\"540634dd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Meet the Animated Stars of AniFuzion!<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a412d3f elementor-widget elementor-widget-text-editor\" data-id=\"a412d3f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tStep into the world of animation with AniFuzion\u2019s <a class=\"white-links-bold\" href=\"https:\/\/www.anifuzion.com\/features\/3d-characters\/\">character families<\/a>! From dynamic 2D to captivating 3D designs, explore a wide range of customizable characters using this powerful online animation tool that will elevate your storytelling.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7727680 elementor-widget elementor-widget-spacer\" data-id=\"7727680\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1e0a537 elementor-widget elementor-widget-image\" data-id=\"1e0a537\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"928\" height=\"525\" src=\"https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/12\/top-screenshot.png\" class=\"attachment-large size-large wp-image-24506\" alt=\"\" srcset=\"https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/12\/top-screenshot.png 928w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/12\/top-screenshot-300x170.png 300w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/12\/top-screenshot-768x434.png 768w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/12\/top-screenshot-600x339.png 600w\" sizes=\"(max-width: 928px) 100vw, 928px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-39e282b elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"39e282b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;gradient&quot;,&quot;shape_divider_bottom&quot;:&quot;triangle&quot;}\">\n\t\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M500,98.9L0,6.1V0h1000v6.1L500,98.9z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e6af837\" data-id=\"e6af837\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-79f36b4 elementor-widget elementor-widget-heading\" data-id=\"79f36b4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Featured Families<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7b9b8dc elementor-widget elementor-widget-text-editor\" data-id=\"7b9b8dc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tUnlock animation magic with AniFuzion, your go-to online animation creator! Design with dynamic 2D and stunning 3D customizable characters to bring your ideas to life.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6d6f52d elementor-widget elementor-widget-spacer\" data-id=\"6d6f52d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4c757cb elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"4c757cb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-e8e3319\" data-id=\"e8e3319\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3c28cb3 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"3c28cb3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.anifuzion.com\/characters\/realistic-family\" tabindex=\"-1\"><img decoding=\"async\" width=\"430\" height=\"430\" src=\"https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/realistic-family-showcase-slide.png\" class=\"attachment-full size-full wp-image-23924\" alt=\"\" srcset=\"https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/realistic-family-showcase-slide.png 430w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/realistic-family-showcase-slide-300x300.png 300w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/realistic-family-showcase-slide-150x150.png 150w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/realistic-family-showcase-slide-80x80.png 80w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/realistic-family-showcase-slide-70x70.png 70w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/realistic-family-showcase-slide-100x100.png 100w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/realistic-family-showcase-slide-370x370.png 370w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/realistic-family-showcase-slide-75x75.png 75w\" sizes=\"(max-width: 430px) 100vw, 430px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.anifuzion.com\/characters\/realistic-family\">Realistic Family<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-8a6560b\" data-id=\"8a6560b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f847da9 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"f847da9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.anifuzion.com\/characters\/manga-vol-1-family\" tabindex=\"-1\"><img decoding=\"async\" width=\"430\" height=\"430\" src=\"https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/manga-vol-1-family-slide.png\" class=\"attachment-full size-full wp-image-23921\" alt=\"\" srcset=\"https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/manga-vol-1-family-slide.png 430w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/manga-vol-1-family-slide-300x300.png 300w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/manga-vol-1-family-slide-150x150.png 150w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/manga-vol-1-family-slide-80x80.png 80w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/manga-vol-1-family-slide-70x70.png 70w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/manga-vol-1-family-slide-100x100.png 100w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/manga-vol-1-family-slide-370x370.png 370w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/manga-vol-1-family-slide-75x75.png 75w\" sizes=\"(max-width: 430px) 100vw, 430px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.anifuzion.com\/characters\/manga-vol-1-family\">Manga Family<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-af7521b\" data-id=\"af7521b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d72c990 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"d72c990\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.anifuzion.com\/characters\/street-people-family\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"430\" height=\"430\" src=\"https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/street-people-family-slide.png\" class=\"attachment-full size-full wp-image-23925\" alt=\"\" srcset=\"https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/street-people-family-slide.png 430w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/street-people-family-slide-300x300.png 300w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/street-people-family-slide-150x150.png 150w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/street-people-family-slide-80x80.png 80w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/street-people-family-slide-70x70.png 70w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/street-people-family-slide-100x100.png 100w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/street-people-family-slide-370x370.png 370w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/street-people-family-slide-75x75.png 75w\" sizes=\"(max-width: 430px) 100vw, 430px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.anifuzion.com\/characters\/street-people-family\">Street People Family<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-5a81144\" data-id=\"5a81144\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0b18d10 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"0b18d10\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.anifuzion.com\/characters\/low-poly-vol-1-family\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"430\" height=\"430\" src=\"https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/low-poly-vol-1-family-slide.png\" class=\"attachment-full size-full wp-image-23919\" alt=\"\" srcset=\"https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/low-poly-vol-1-family-slide.png 430w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/low-poly-vol-1-family-slide-300x300.png 300w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/low-poly-vol-1-family-slide-150x150.png 150w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/low-poly-vol-1-family-slide-80x80.png 80w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/low-poly-vol-1-family-slide-70x70.png 70w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/low-poly-vol-1-family-slide-100x100.png 100w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/low-poly-vol-1-family-slide-370x370.png 370w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/low-poly-vol-1-family-slide-75x75.png 75w\" sizes=\"(max-width: 430px) 100vw, 430px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.anifuzion.com\/characters\/low-poly-vol-1-family\">Low Poly Family<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-397b511 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"397b511\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;gradient&quot;,&quot;shape_divider_bottom&quot;:&quot;waves&quot;}\">\n\t\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M421.9,6.5c22.6-2.5,51.5,0.4,75.5,5.3c23.6,4.9,70.9,23.5,100.5,35.7c75.8,32.2,133.7,44.5,192.6,49.7\n\tc23.6,2.1,48.7,3.5,103.4-2.5c54.7-6,106.2-25.6,106.2-25.6V0H0v30.3c0,0,72,32.6,158.4,30.5c39.2-0.7,92.8-6.7,134-22.4\n\tc21.2-8.1,52.2-18.2,79.7-24.2C399.3,7.9,411.6,7.5,421.9,6.5z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-145d8b2\" data-id=\"145d8b2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0aee0e4 elementor-widget elementor-widget-heading\" data-id=\"0aee0e4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Anime and Cartoon<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-24cb267 elementor-widget elementor-widget-text-editor\" data-id=\"24cb267\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tBring Anime and Cartoon characters to life with AniFuzion, your trusted online animation maker! Create vibrant, customizable character families in dynamic 2D and immersive 3D\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-92c67d7 elementor-widget elementor-widget-spacer\" data-id=\"92c67d7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-9bb4aa5 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"9bb4aa5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-c2c6c19\" data-id=\"c2c6c19\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7cfa364 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"7cfa364\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.anifuzion.com\/characters\/manga-vol-1-family\" tabindex=\"-1\"><img decoding=\"async\" width=\"430\" height=\"430\" src=\"https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/manga-vol-1-family-slide.png\" class=\"attachment-full size-full wp-image-23921\" alt=\"\" srcset=\"https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/manga-vol-1-family-slide.png 430w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/manga-vol-1-family-slide-300x300.png 300w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/manga-vol-1-family-slide-150x150.png 150w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/manga-vol-1-family-slide-80x80.png 80w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/manga-vol-1-family-slide-70x70.png 70w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/manga-vol-1-family-slide-100x100.png 100w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/manga-vol-1-family-slide-370x370.png 370w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/manga-vol-1-family-slide-75x75.png 75w\" sizes=\"(max-width: 430px) 100vw, 430px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.anifuzion.com\/characters\/manga-vol-1-family\">Manga Vol 1 Family<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-84207a7\" data-id=\"84207a7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d2f0005 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"d2f0005\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.anifuzion.com\/characters\/manga-vol-2-family\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"430\" height=\"430\" src=\"https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/manga-vol-2-family-slide.png\" class=\"attachment-full size-full wp-image-23922\" alt=\"\" srcset=\"https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/manga-vol-2-family-slide.png 430w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/manga-vol-2-family-slide-300x300.png 300w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/manga-vol-2-family-slide-150x150.png 150w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/manga-vol-2-family-slide-80x80.png 80w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/manga-vol-2-family-slide-70x70.png 70w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/manga-vol-2-family-slide-100x100.png 100w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/manga-vol-2-family-slide-370x370.png 370w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/manga-vol-2-family-slide-75x75.png 75w\" sizes=\"(max-width: 430px) 100vw, 430px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.anifuzion.com\/characters\/manga-vol-2-family\">Manga Vol 2 Family<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-0eb2282\" data-id=\"0eb2282\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-28ace05 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"28ace05\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.anifuzion.com\/characters\/jumbloo-family\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"430\" height=\"430\" src=\"https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/jumbloo-jumbloo-family-slide.png\" class=\"attachment-full size-full wp-image-23918\" alt=\"\" srcset=\"https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/jumbloo-jumbloo-family-slide.png 430w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/jumbloo-jumbloo-family-slide-300x300.png 300w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/jumbloo-jumbloo-family-slide-150x150.png 150w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/jumbloo-jumbloo-family-slide-80x80.png 80w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/jumbloo-jumbloo-family-slide-70x70.png 70w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/jumbloo-jumbloo-family-slide-100x100.png 100w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/jumbloo-jumbloo-family-slide-370x370.png 370w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/jumbloo-jumbloo-family-slide-75x75.png 75w\" sizes=\"(max-width: 430px) 100vw, 430px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.anifuzion.com\/characters\/jumbloo-family\">Jumbloo Family<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-e23b858\" data-id=\"e23b858\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e1d2c25 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"e1d2c25\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.anifuzion.com\/characters\/toon-vol-1-family\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"430\" height=\"430\" src=\"https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/toon-vol-1-family-slide.png\" class=\"attachment-full size-full wp-image-23927\" alt=\"\" srcset=\"https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/toon-vol-1-family-slide.png 430w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/toon-vol-1-family-slide-300x300.png 300w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/toon-vol-1-family-slide-150x150.png 150w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/toon-vol-1-family-slide-80x80.png 80w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/toon-vol-1-family-slide-70x70.png 70w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/toon-vol-1-family-slide-100x100.png 100w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/toon-vol-1-family-slide-370x370.png 370w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/toon-vol-1-family-slide-75x75.png 75w\" sizes=\"(max-width: 430px) 100vw, 430px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.anifuzion.com\/characters\/toon-vol-1-family\">Toon Vol 1 Family<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6d2486d elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"6d2486d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-e079aad\" data-id=\"e079aad\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-52c013b elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"52c013b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.anifuzion.com\/characters\/toon-vol-2-family\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"430\" height=\"430\" src=\"https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/toon-vol-2-family-slide.png\" class=\"attachment-full size-full wp-image-23928\" alt=\"\" srcset=\"https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/toon-vol-2-family-slide.png 430w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/toon-vol-2-family-slide-300x300.png 300w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/toon-vol-2-family-slide-150x150.png 150w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/toon-vol-2-family-slide-80x80.png 80w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/toon-vol-2-family-slide-70x70.png 70w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/toon-vol-2-family-slide-100x100.png 100w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/toon-vol-2-family-slide-370x370.png 370w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/toon-vol-2-family-slide-75x75.png 75w\" sizes=\"(max-width: 430px) 100vw, 430px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.anifuzion.com\/characters\/toon-vol-2-family\">Toon Vol 2 Family<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-dd67b8d\" data-id=\"dd67b8d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2b131b4 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"2b131b4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.anifuzion.com\/characters\/pirate-kit-family\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"430\" height=\"430\" src=\"https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/pirate-kit-family-showcase-slide.png\" class=\"attachment-full size-full wp-image-23923\" alt=\"\" srcset=\"https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/pirate-kit-family-showcase-slide.png 430w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/pirate-kit-family-showcase-slide-300x300.png 300w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/pirate-kit-family-showcase-slide-150x150.png 150w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/pirate-kit-family-showcase-slide-80x80.png 80w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/pirate-kit-family-showcase-slide-70x70.png 70w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/pirate-kit-family-showcase-slide-100x100.png 100w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/pirate-kit-family-showcase-slide-370x370.png 370w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/pirate-kit-family-showcase-slide-75x75.png 75w\" sizes=\"(max-width: 430px) 100vw, 430px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.anifuzion.com\/characters\/pirate-kit-family\">Pirate Kit Family<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-40297d6\" data-id=\"40297d6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-746fc43 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"746fc43\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.anifuzion.com\/characters\/sushi-clan-family\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"430\" height=\"430\" src=\"https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/sushi-clan-family-showcase-slide.png\" class=\"attachment-full size-full wp-image-23926\" alt=\"\" srcset=\"https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/sushi-clan-family-showcase-slide.png 430w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/sushi-clan-family-showcase-slide-300x300.png 300w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/sushi-clan-family-showcase-slide-150x150.png 150w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/sushi-clan-family-showcase-slide-80x80.png 80w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/sushi-clan-family-showcase-slide-70x70.png 70w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/sushi-clan-family-showcase-slide-100x100.png 100w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/sushi-clan-family-showcase-slide-370x370.png 370w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/sushi-clan-family-showcase-slide-75x75.png 75w\" sizes=\"(max-width: 430px) 100vw, 430px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.anifuzion.com\/characters\/sushi-clan-family\">Sushi Clan Family<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-648b32a\" data-id=\"648b32a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e0b163e elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"e0b163e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.anifuzion.com\/characters\/chibi-family\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"430\" height=\"430\" src=\"https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/12\/chibi-family-showcase-slide.png\" class=\"attachment-full size-full wp-image-24449\" alt=\"\" srcset=\"https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/12\/chibi-family-showcase-slide.png 430w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/12\/chibi-family-showcase-slide-300x300.png 300w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/12\/chibi-family-showcase-slide-150x150.png 150w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/12\/chibi-family-showcase-slide-80x80.png 80w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/12\/chibi-family-showcase-slide-70x70.png 70w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/12\/chibi-family-showcase-slide-100x100.png 100w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/12\/chibi-family-showcase-slide-370x370.png 370w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/12\/chibi-family-showcase-slide-75x75.png 75w\" sizes=\"(max-width: 430px) 100vw, 430px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.anifuzion.com\/characters\/chibi-family\">Chibi Family<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5a70f9a elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"5a70f9a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-ae68605\" data-id=\"ae68605\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0b5487f elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"0b5487f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.anifuzion.com\/characters\/adventurer-family\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"430\" height=\"430\" src=\"https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/12\/adventurer-family-showcase-slide.png\" class=\"attachment-full size-full wp-image-24453\" alt=\"\" srcset=\"https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/12\/adventurer-family-showcase-slide.png 430w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/12\/adventurer-family-showcase-slide-300x300.png 300w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/12\/adventurer-family-showcase-slide-150x150.png 150w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/12\/adventurer-family-showcase-slide-80x80.png 80w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/12\/adventurer-family-showcase-slide-70x70.png 70w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/12\/adventurer-family-showcase-slide-100x100.png 100w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/12\/adventurer-family-showcase-slide-370x370.png 370w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/12\/adventurer-family-showcase-slide-75x75.png 75w\" sizes=\"(max-width: 430px) 100vw, 430px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.anifuzion.com\/characters\/adventurer-family\">Adventurer Family<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-a13c7e0\" data-id=\"a13c7e0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e763f69 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"e763f69\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.anifuzion.com\/characters\/dream-squad-family\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"430\" height=\"430\" src=\"https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/dream-squad-family-slide.png\" class=\"attachment-full size-full wp-image-23916\" alt=\"\" srcset=\"https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/dream-squad-family-slide.png 430w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/dream-squad-family-slide-300x300.png 300w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/dream-squad-family-slide-150x150.png 150w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/dream-squad-family-slide-80x80.png 80w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/dream-squad-family-slide-70x70.png 70w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/dream-squad-family-slide-100x100.png 100w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/dream-squad-family-slide-370x370.png 370w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/dream-squad-family-slide-75x75.png 75w\" sizes=\"(max-width: 430px) 100vw, 430px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.anifuzion.com\/characters\/dream-squad-family\">Dream Squad Family<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-c833251\" data-id=\"c833251\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-90caf37 hidden elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"90caf37\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"430\" height=\"430\" src=\"https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/sushi-clan-family-showcase-slide.png\" class=\"attachment-full size-full wp-image-23926\" alt=\"\" srcset=\"https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/sushi-clan-family-showcase-slide.png 430w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/sushi-clan-family-showcase-slide-300x300.png 300w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/sushi-clan-family-showcase-slide-150x150.png 150w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/sushi-clan-family-showcase-slide-80x80.png 80w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/sushi-clan-family-showcase-slide-70x70.png 70w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/sushi-clan-family-showcase-slide-100x100.png 100w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/sushi-clan-family-showcase-slide-370x370.png 370w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/sushi-clan-family-showcase-slide-75x75.png 75w\" sizes=\"(max-width: 430px) 100vw, 430px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Sushi Clan Family<\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-eb6a936\" data-id=\"eb6a936\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f7b5ed1 hidden elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"f7b5ed1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"430\" height=\"430\" src=\"https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/12\/chibi-family-showcase-slide.png\" class=\"attachment-full size-full wp-image-24449\" alt=\"\" srcset=\"https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/12\/chibi-family-showcase-slide.png 430w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/12\/chibi-family-showcase-slide-300x300.png 300w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/12\/chibi-family-showcase-slide-150x150.png 150w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/12\/chibi-family-showcase-slide-80x80.png 80w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/12\/chibi-family-showcase-slide-70x70.png 70w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/12\/chibi-family-showcase-slide-100x100.png 100w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/12\/chibi-family-showcase-slide-370x370.png 370w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/12\/chibi-family-showcase-slide-75x75.png 75w\" sizes=\"(max-width: 430px) 100vw, 430px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Chibi Family<\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-112d422 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"112d422\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;gradient&quot;,&quot;shape_divider_bottom&quot;:&quot;triangle&quot;}\">\n\t\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M500,98.9L0,6.1V0h1000v6.1L500,98.9z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c199d46\" data-id=\"c199d46\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-344c81c elementor-widget elementor-widget-heading\" data-id=\"344c81c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Low Poly<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-51d5574 elementor-widget elementor-widget-text-editor\" data-id=\"51d5574\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tBring simplicity and style together with AniFuzion\u2019s Low Poly Character Family! As your go-to online animation maker, craft customizable, minimalist characters in dynamic 2D and stunning 3D to enhance your creative projects.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e619df0 elementor-widget elementor-widget-spacer\" data-id=\"e619df0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-389e8f1 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"389e8f1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-eee59c6\" data-id=\"eee59c6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fd98ea5 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"fd98ea5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.anifuzion.com\/characters\/low-poly-vol-1-family\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"430\" height=\"430\" src=\"https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/low-poly-vol-1-family-slide.png\" class=\"attachment-full size-full wp-image-23919\" alt=\"\" srcset=\"https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/low-poly-vol-1-family-slide.png 430w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/low-poly-vol-1-family-slide-300x300.png 300w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/low-poly-vol-1-family-slide-150x150.png 150w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/low-poly-vol-1-family-slide-80x80.png 80w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/low-poly-vol-1-family-slide-70x70.png 70w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/low-poly-vol-1-family-slide-100x100.png 100w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/low-poly-vol-1-family-slide-370x370.png 370w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/low-poly-vol-1-family-slide-75x75.png 75w\" sizes=\"(max-width: 430px) 100vw, 430px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.anifuzion.com\/characters\/low-poly-vol-1-family\">Low Poly Vol 1 Family<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-3ba1be5\" data-id=\"3ba1be5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ccec961 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"ccec961\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.anifuzion.com\/characters\/low-poly-vol-2-family\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"430\" height=\"430\" src=\"https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/low-poly-vol-2-family-slide.png\" class=\"attachment-full size-full wp-image-23920\" alt=\"\" srcset=\"https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/low-poly-vol-2-family-slide.png 430w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/low-poly-vol-2-family-slide-300x300.png 300w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/low-poly-vol-2-family-slide-150x150.png 150w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/low-poly-vol-2-family-slide-80x80.png 80w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/low-poly-vol-2-family-slide-70x70.png 70w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/low-poly-vol-2-family-slide-100x100.png 100w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/low-poly-vol-2-family-slide-370x370.png 370w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/low-poly-vol-2-family-slide-75x75.png 75w\" sizes=\"(max-width: 430px) 100vw, 430px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.anifuzion.com\/characters\/low-poly-vol-2-family\">Low Poly Vol 2 Family<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-3db4559\" data-id=\"3db4559\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0db1d58 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"0db1d58\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.anifuzion.com\/characters\/voxel-family\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"430\" height=\"430\" src=\"https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/voxel-family-showcase-slide.png\" class=\"attachment-full size-full wp-image-23929\" alt=\"\" srcset=\"https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/voxel-family-showcase-slide.png 430w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/voxel-family-showcase-slide-300x300.png 300w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/voxel-family-showcase-slide-150x150.png 150w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/voxel-family-showcase-slide-80x80.png 80w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/voxel-family-showcase-slide-70x70.png 70w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/voxel-family-showcase-slide-100x100.png 100w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/voxel-family-showcase-slide-370x370.png 370w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/voxel-family-showcase-slide-75x75.png 75w\" sizes=\"(max-width: 430px) 100vw, 430px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.anifuzion.com\/characters\/voxel-family\">Voxel Family<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-380c9de\" data-id=\"380c9de\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f6601e0 hidden elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"f6601e0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.anifuzion.com\/characters\/buddies-family\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"430\" height=\"430\" src=\"https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/buddies-vol-1-family-showcase-slide.png\" class=\"attachment-full size-full wp-image-23912\" alt=\"\" srcset=\"https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/buddies-vol-1-family-showcase-slide.png 430w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/buddies-vol-1-family-showcase-slide-300x300.png 300w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/buddies-vol-1-family-showcase-slide-150x150.png 150w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/buddies-vol-1-family-showcase-slide-80x80.png 80w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/buddies-vol-1-family-showcase-slide-70x70.png 70w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/buddies-vol-1-family-showcase-slide-100x100.png 100w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/buddies-vol-1-family-showcase-slide-370x370.png 370w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/buddies-vol-1-family-showcase-slide-75x75.png 75w\" sizes=\"(max-width: 430px) 100vw, 430px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.anifuzion.com\/characters\/buddies-family\">Low Poly Animal Family<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2766680 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"2766680\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;gradient&quot;,&quot;shape_divider_bottom&quot;:&quot;triangle&quot;}\">\n\t\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M500,98.9L0,6.1V0h1000v6.1L500,98.9z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5c62b33\" data-id=\"5c62b33\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-94cb13d elementor-widget elementor-widget-heading\" data-id=\"94cb13d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Cute and Fun<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f3c4447 elementor-widget elementor-widget-text-editor\" data-id=\"f3c4447\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tAdd charm and playfulness to your animations with AniFuzion\u2019s Cute and Fun Character Family! This online animation tool lets you design delightful, customizable characters in both vibrant 2D and engaging 3D.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a4d85d8 elementor-widget elementor-widget-spacer\" data-id=\"a4d85d8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-d4d8550 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"d4d8550\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-b9df099\" data-id=\"b9df099\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-edf8db0 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"edf8db0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.anifuzion.com\/characters\/clay-family\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"430\" height=\"430\" src=\"https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/clay-family-showcase-slide.png\" class=\"attachment-full size-full wp-image-23914\" alt=\"\" srcset=\"https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/clay-family-showcase-slide.png 430w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/clay-family-showcase-slide-300x300.png 300w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/clay-family-showcase-slide-150x150.png 150w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/clay-family-showcase-slide-80x80.png 80w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/clay-family-showcase-slide-70x70.png 70w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/clay-family-showcase-slide-100x100.png 100w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/clay-family-showcase-slide-370x370.png 370w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/clay-family-showcase-slide-75x75.png 75w\" sizes=\"(max-width: 430px) 100vw, 430px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.anifuzion.com\/characters\/clay-family\">Clay Family<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-ee68057\" data-id=\"ee68057\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3e13327 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"3e13327\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.anifuzion.com\/characters\/biz-fam-family\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"430\" height=\"430\" src=\"https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/biz-fam-family-showcase-slide.png\" class=\"attachment-full size-full wp-image-23910\" alt=\"\" srcset=\"https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/biz-fam-family-showcase-slide.png 430w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/biz-fam-family-showcase-slide-300x300.png 300w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/biz-fam-family-showcase-slide-150x150.png 150w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/biz-fam-family-showcase-slide-80x80.png 80w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/biz-fam-family-showcase-slide-70x70.png 70w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/biz-fam-family-showcase-slide-100x100.png 100w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/biz-fam-family-showcase-slide-370x370.png 370w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/biz-fam-family-showcase-slide-75x75.png 75w\" sizes=\"(max-width: 430px) 100vw, 430px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.anifuzion.com\/characters\/biz-fam-family\">Biz Family<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-c69be62\" data-id=\"c69be62\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9bb6c8c elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"9bb6c8c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.anifuzion.com\/characters\/color-crew-family\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"430\" height=\"430\" src=\"https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/color-crew-family-showcase-slide.png\" class=\"attachment-full size-full wp-image-23915\" alt=\"\" srcset=\"https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/color-crew-family-showcase-slide.png 430w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/color-crew-family-showcase-slide-300x300.png 300w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/color-crew-family-showcase-slide-150x150.png 150w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/color-crew-family-showcase-slide-80x80.png 80w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/color-crew-family-showcase-slide-70x70.png 70w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/color-crew-family-showcase-slide-100x100.png 100w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/color-crew-family-showcase-slide-370x370.png 370w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/color-crew-family-showcase-slide-75x75.png 75w\" sizes=\"(max-width: 430px) 100vw, 430px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.anifuzion.com\/characters\/color-crew-family\">Color Crew Family<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-7c3a164\" data-id=\"7c3a164\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f2288e2 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"f2288e2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.anifuzion.com\/characters\/buddies-family\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"430\" height=\"430\" src=\"https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/buddies-family-showcase-slide.png\" class=\"attachment-full size-full wp-image-23911\" alt=\"\" srcset=\"https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/buddies-family-showcase-slide.png 430w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/buddies-family-showcase-slide-300x300.png 300w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/buddies-family-showcase-slide-150x150.png 150w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/buddies-family-showcase-slide-80x80.png 80w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/buddies-family-showcase-slide-70x70.png 70w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/buddies-family-showcase-slide-100x100.png 100w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/buddies-family-showcase-slide-370x370.png 370w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/buddies-family-showcase-slide-75x75.png 75w\" sizes=\"(max-width: 430px) 100vw, 430px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.anifuzion.com\/characters\/buddies-family\">Buddies 1 Family<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e5452cd elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"e5452cd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-755b66f\" data-id=\"755b66f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c0a83f8 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"c0a83f8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.anifuzion.com\/characters\/buddies-vol-2-family\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"430\" height=\"430\" src=\"https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/buddies-vol-2-family-showcase-slide.png\" class=\"attachment-full size-full wp-image-23913\" alt=\"\" srcset=\"https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/buddies-vol-2-family-showcase-slide.png 430w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/buddies-vol-2-family-showcase-slide-300x300.png 300w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/buddies-vol-2-family-showcase-slide-150x150.png 150w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/buddies-vol-2-family-showcase-slide-80x80.png 80w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/buddies-vol-2-family-showcase-slide-70x70.png 70w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/buddies-vol-2-family-showcase-slide-100x100.png 100w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/buddies-vol-2-family-showcase-slide-370x370.png 370w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/buddies-vol-2-family-showcase-slide-75x75.png 75w\" sizes=\"(max-width: 430px) 100vw, 430px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.anifuzion.com\/characters\/buddies-vol-2-family\">Buddies Vol 2 Family<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-514b408\" data-id=\"514b408\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9766d64 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"9766d64\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.anifuzion.com\/characters\/buddies-vol-1-family\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"430\" height=\"430\" src=\"https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/buddies-vol-1-family-showcase-slide.png\" class=\"attachment-full size-full wp-image-23912\" alt=\"\" srcset=\"https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/buddies-vol-1-family-showcase-slide.png 430w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/buddies-vol-1-family-showcase-slide-300x300.png 300w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/buddies-vol-1-family-showcase-slide-150x150.png 150w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/buddies-vol-1-family-showcase-slide-80x80.png 80w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/buddies-vol-1-family-showcase-slide-70x70.png 70w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/buddies-vol-1-family-showcase-slide-100x100.png 100w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/buddies-vol-1-family-showcase-slide-370x370.png 370w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/buddies-vol-1-family-showcase-slide-75x75.png 75w\" sizes=\"(max-width: 430px) 100vw, 430px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.anifuzion.com\/characters\/buddies-vol-1-family\">Buddies Vol 1 Family<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-91ded8a\" data-id=\"91ded8a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c0355d9 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"c0355d9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.anifuzion.com\/characters\/street-people-vol-2-family\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"430\" height=\"430\" src=\"https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/12\/street-people-2-family-showcase-slide.png\" class=\"attachment-full size-full wp-image-25531\" alt=\"\" srcset=\"https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/12\/street-people-2-family-showcase-slide.png 430w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/12\/street-people-2-family-showcase-slide-300x300.png 300w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/12\/street-people-2-family-showcase-slide-150x150.png 150w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/12\/street-people-2-family-showcase-slide-80x80.png 80w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/12\/street-people-2-family-showcase-slide-70x70.png 70w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/12\/street-people-2-family-showcase-slide-100x100.png 100w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/12\/street-people-2-family-showcase-slide-370x370.png 370w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/12\/street-people-2-family-showcase-slide-75x75.png 75w\" sizes=\"(max-width: 430px) 100vw, 430px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.anifuzion.com\/characters\/street-people-vol-2-family\">Street People Vol 2<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-c9127d3\" data-id=\"c9127d3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5f98351 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"5f98351\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;gradient&quot;,&quot;shape_divider_bottom&quot;:&quot;triangle&quot;}\">\n\t\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M500,98.9L0,6.1V0h1000v6.1L500,98.9z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7dd5aec\" data-id=\"7dd5aec\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3e93423 elementor-widget elementor-widget-heading\" data-id=\"3e93423\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Fantasy and Misc<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-16a832a elementor-widget elementor-widget-text-editor\" data-id=\"16a832a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tTransform your creative vision with AniFuzion\u2019s Fantasy and Misc Character Family! This online animation maker offers a diverse range of customizable characters in magical 2D and stunning 3D styles.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9a34b76 elementor-widget elementor-widget-spacer\" data-id=\"9a34b76\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c793909 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"c793909\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-bf703fc\" data-id=\"bf703fc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-44bc327 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"44bc327\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.anifuzion.com\/characters\/fantasy-family\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"430\" height=\"430\" src=\"https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/fantasy-family-showcase-slide.png\" class=\"attachment-full size-full wp-image-23917\" alt=\"\" srcset=\"https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/fantasy-family-showcase-slide.png 430w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/fantasy-family-showcase-slide-300x300.png 300w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/fantasy-family-showcase-slide-150x150.png 150w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/fantasy-family-showcase-slide-80x80.png 80w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/fantasy-family-showcase-slide-70x70.png 70w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/fantasy-family-showcase-slide-100x100.png 100w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/fantasy-family-showcase-slide-370x370.png 370w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/fantasy-family-showcase-slide-75x75.png 75w\" sizes=\"(max-width: 430px) 100vw, 430px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.anifuzion.com\/characters\/fantasy-family\">Fantasy Family<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-69eef32\" data-id=\"69eef32\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-180ed06 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"180ed06\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.anifuzion.com\/characters\/spacekit-family\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"430\" height=\"430\" src=\"https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/12\/spacekit-family-showcase-slide.png\" class=\"attachment-full size-full wp-image-24926\" alt=\"\" srcset=\"https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/12\/spacekit-family-showcase-slide.png 430w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/12\/spacekit-family-showcase-slide-300x300.png 300w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/12\/spacekit-family-showcase-slide-150x150.png 150w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/12\/spacekit-family-showcase-slide-80x80.png 80w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/12\/spacekit-family-showcase-slide-70x70.png 70w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/12\/spacekit-family-showcase-slide-100x100.png 100w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/12\/spacekit-family-showcase-slide-370x370.png 370w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/12\/spacekit-family-showcase-slide-75x75.png 75w\" sizes=\"(max-width: 430px) 100vw, 430px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.anifuzion.com\/characters\/spacekit-family\">SpaceKit Family<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-c0d6ab6\" data-id=\"c0d6ab6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f600a05 hidden elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"f600a05\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.anifuzion.com\/characters\/shade-family\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"430\" height=\"430\" src=\"https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/12\/shade-family-showcase-slide.png\" class=\"attachment-full size-full wp-image-25228\" alt=\"\" srcset=\"https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/12\/shade-family-showcase-slide.png 430w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/12\/shade-family-showcase-slide-300x300.png 300w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/12\/shade-family-showcase-slide-150x150.png 150w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/12\/shade-family-showcase-slide-80x80.png 80w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/12\/shade-family-showcase-slide-70x70.png 70w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/12\/shade-family-showcase-slide-100x100.png 100w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/12\/shade-family-showcase-slide-370x370.png 370w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/12\/shade-family-showcase-slide-75x75.png 75w\" sizes=\"(max-width: 430px) 100vw, 430px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.anifuzion.com\/characters\/shade-family\">Shade Family<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-c4c759e\" data-id=\"c4c759e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f1714f8 hidden elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"f1714f8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"430\" height=\"430\" src=\"https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/buddies-vol-2-family-showcase-slide.png\" class=\"attachment-full size-full wp-image-23913\" alt=\"\" srcset=\"https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/buddies-vol-2-family-showcase-slide.png 430w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/buddies-vol-2-family-showcase-slide-300x300.png 300w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/buddies-vol-2-family-showcase-slide-150x150.png 150w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/buddies-vol-2-family-showcase-slide-80x80.png 80w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/buddies-vol-2-family-showcase-slide-70x70.png 70w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/buddies-vol-2-family-showcase-slide-100x100.png 100w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/buddies-vol-2-family-showcase-slide-370x370.png 370w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/buddies-vol-2-family-showcase-slide-75x75.png 75w\" sizes=\"(max-width: 430px) 100vw, 430px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Janny Doe, Director<\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3260ca7 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"3260ca7\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d8e8f9a\" data-id=\"d8e8f9a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3f0a51a elementor-widget elementor-widget-heading\" data-id=\"3f0a51a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Animals<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d1cbd66 elementor-widget elementor-widget-text-editor\" data-id=\"d1cbd66\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tExplore endless possibilities with AniFuzion\u2019s Animals Character Family! This online animation tool lets you craft unique, customizable animal characters in lively 2D and realistic 3D formats.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f4db743 elementor-widget elementor-widget-spacer\" data-id=\"f4db743\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2e602c1 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"2e602c1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-156ef59\" data-id=\"156ef59\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-71ed36a elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"71ed36a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.anifuzion.com\/characters\/cute-animals-family\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"430\" height=\"430\" src=\"https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/12\/cute-animals-family-showcase-slide.png\" class=\"attachment-full size-full wp-image-24886\" alt=\"\" srcset=\"https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/12\/cute-animals-family-showcase-slide.png 430w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/12\/cute-animals-family-showcase-slide-300x300.png 300w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/12\/cute-animals-family-showcase-slide-150x150.png 150w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/12\/cute-animals-family-showcase-slide-80x80.png 80w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/12\/cute-animals-family-showcase-slide-70x70.png 70w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/12\/cute-animals-family-showcase-slide-100x100.png 100w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/12\/cute-animals-family-showcase-slide-370x370.png 370w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/12\/cute-animals-family-showcase-slide-75x75.png 75w\" sizes=\"(max-width: 430px) 100vw, 430px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.anifuzion.com\/characters\/cute-animals-family\">Cute Animals<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-1542e00\" data-id=\"1542e00\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d1cf318 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"d1cf318\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.anifuzion.com\/characters\/low-poly-animals-family\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"430\" height=\"430\" src=\"https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2025\/01\/low-poly-animals-showcase-slide.png\" class=\"attachment-full size-full wp-image-27505\" alt=\"\" srcset=\"https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2025\/01\/low-poly-animals-showcase-slide.png 430w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2025\/01\/low-poly-animals-showcase-slide-300x300.png 300w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2025\/01\/low-poly-animals-showcase-slide-150x150.png 150w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2025\/01\/low-poly-animals-showcase-slide-80x80.png 80w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2025\/01\/low-poly-animals-showcase-slide-70x70.png 70w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2025\/01\/low-poly-animals-showcase-slide-100x100.png 100w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2025\/01\/low-poly-animals-showcase-slide-370x370.png 370w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2025\/01\/low-poly-animals-showcase-slide-75x75.png 75w\" sizes=\"(max-width: 430px) 100vw, 430px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.anifuzion.com\/characters\/low-poly-animals-family\">Low Poly Animals<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-5f4def3\" data-id=\"5f4def3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-42e19d9 hidden elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"42e19d9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.anifuzion.com\/characters\/shade-family\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"430\" height=\"430\" src=\"https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/12\/shade-family-showcase-slide.png\" class=\"attachment-full size-full wp-image-25228\" alt=\"\" srcset=\"https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/12\/shade-family-showcase-slide.png 430w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/12\/shade-family-showcase-slide-300x300.png 300w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/12\/shade-family-showcase-slide-150x150.png 150w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/12\/shade-family-showcase-slide-80x80.png 80w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/12\/shade-family-showcase-slide-70x70.png 70w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/12\/shade-family-showcase-slide-100x100.png 100w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/12\/shade-family-showcase-slide-370x370.png 370w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/12\/shade-family-showcase-slide-75x75.png 75w\" sizes=\"(max-width: 430px) 100vw, 430px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.anifuzion.com\/characters\/shade-family\">Shade Family<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-97eecd1\" data-id=\"97eecd1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5048dd0 hidden elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"5048dd0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"430\" height=\"430\" src=\"https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/buddies-vol-2-family-showcase-slide.png\" class=\"attachment-full size-full wp-image-23913\" alt=\"\" srcset=\"https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/buddies-vol-2-family-showcase-slide.png 430w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/buddies-vol-2-family-showcase-slide-300x300.png 300w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/buddies-vol-2-family-showcase-slide-150x150.png 150w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/buddies-vol-2-family-showcase-slide-80x80.png 80w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/buddies-vol-2-family-showcase-slide-70x70.png 70w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/buddies-vol-2-family-showcase-slide-100x100.png 100w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/buddies-vol-2-family-showcase-slide-370x370.png 370w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/11\/buddies-vol-2-family-showcase-slide-75x75.png 75w\" sizes=\"(max-width: 430px) 100vw, 430px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Janny Doe, Director<\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<div class=\"premium-shape-divider__shape-container\" id=\"premium-shape-divider-31d3a6f9\" style=\"visibility:hidden; position: absolute; opacity:0;\">\r\n\t\t\t\t\t<svg xmlns='http:\/\/www.w3.org\/2000\/svg' aria-hidden='true' viewBox='0 0 35.28 2.17' preserveAspectRatio='none'><path d='M35.28 1.67c-3.07-.55-9.27.41-16.15 0-6.87-.4-13.74-.58-19.13.1v.4h35.28z' fill='%23fbd8c2'\/><path d='M35.28 1.16c-3.17-.8-7.3.4-10.04.56-2.76.17-9.25-1.47-12.68-1.3-3.42.16-4.64.84-7.04.86C3.12 1.31 0 .4 0 .4v1.77h35.28z' opacity='.5' fill='%23fbd8c2'\/><path d='M35.28.31c-2.57.84-7.68.3-11.8.43-4.1.12-6.85.61-9.57.28C11.18.69 8.3-.16 5.3.02 2.3.22.57.85 0 .87v1.2h35.28z' opacity='.5' fill='%23fbd8c2'\/><\/svg>\t\t\t\t<\/div>\r\n\t\t\t<div class=\"elementor-element elementor-element-31d3a6f9 premium-shape-divider-yes premium-shape20 e-flex e-con-boxed premium-shape-divider__default premium-shape-divider-anime-yes wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-parent\" data-id=\"31d3a6f9\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6df9813a elementor-widget elementor-widget-heading\" data-id=\"6df9813a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">EASY TO USE<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2ebb8087 premium-header-block premium-title-first-noise-yes premium-lq__none premium-box-lq__none elementor-widget elementor-widget-premium-addon-dual-header\" data-id=\"2ebb8087\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"premium-addon-dual-header.default\">\n\t\t\t\t\t\n\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"premium-dual-header-first-header \"><span class=\"premium-dual-header-first-span\" data-text=\"No More \">No More <\/span><span class=\"premium-dual-header-second-header \">Software Hassles!<\/span><\/h1> \t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fc4bf53 elementor-widget elementor-widget-text-editor\" data-id=\"fc4bf53\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tUnlock your creativity with a click. Discover a variety of features, effects, and templates to bring your vision to life, including dynamic 2D and 3D characters.\n\n\n\n\n\n\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-253965ac elementor-widget elementor-widget-spacer\" data-id=\"253965ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4f54cca elementor-widget elementor-widget-image\" data-id=\"4f54cca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"929\" height=\"497\" src=\"https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/07\/easy-to-use-1.png\" class=\"attachment-large size-large wp-image-20450\" alt=\"\" srcset=\"https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/07\/easy-to-use-1.png 929w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/07\/easy-to-use-1-300x160.png 300w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/07\/easy-to-use-1-768x411.png 768w, https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/07\/easy-to-use-1-600x321.png 600w\" sizes=\"(max-width: 929px) 100vw, 929px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-871d2bd elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"871d2bd\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-2aa71af\" data-id=\"2aa71af\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3036fb3 elementor-view-stacked drdt-ignore-dark elementor-shape-circle elementor-widget elementor-widget-icon\" data-id=\"3036fb3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-star\" viewBox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M259.3 17.8L194 150.2 47.9 171.5c-26.2 3.8-36.7 36.1-17.7 54.6l105.7 103-25 145.5c-4.5 26.3 23.2 46 46.4 33.7L288 439.6l130.7 68.7c23.2 12.2 50.9-7.4 46.4-33.7l-25-145.5 105.7-103c19-18.5 8.5-50.8-17.7-54.6L382 150.2 316.7 17.8c-11.7-23.6-45.6-23.9-57.4 0z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-06bf803 elementor-widget elementor-widget-heading\" data-id=\"06bf803\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"#\">Easy to Use<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e25ab1a elementor-widget elementor-widget-heading\" data-id=\"e25ab1a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Effortless simplicity for professional-quality animations.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-c0eb5e4\" data-id=\"c0eb5e4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9358bb6 elementor-view-stacked drdt-ignore-dark elementor-shape-circle elementor-widget elementor-widget-icon\" data-id=\"9358bb6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-feather-alt\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M512 0C460.22 3.56 96.44 38.2 71.01 287.61c-3.09 26.66-4.84 53.44-5.99 80.24l178.87-178.69c6.25-6.25 16.4-6.25 22.65 0s6.25 16.38 0 22.63L7.04 471.03c-9.38 9.37-9.38 24.57 0 33.94 9.38 9.37 24.59 9.37 33.98 0l57.13-57.07c42.09-.14 84.15-2.53 125.96-7.36 53.48-5.44 97.02-26.47 132.58-56.54H255.74l146.79-48.88c11.25-14.89 21.37-30.71 30.45-47.12h-81.14l106.54-53.21C500.29 132.86 510.19 26.26 512 0z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6d91767 elementor-widget elementor-widget-heading\" data-id=\"6d91767\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"#\">Lightweight<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0c417be elementor-widget elementor-widget-heading\" data-id=\"0c417be\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Lightweight video creation without the hassle of installation.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-ba2c7db\" data-id=\"ba2c7db\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-31ad490 elementor-view-stacked drdt-ignore-dark elementor-shape-circle elementor-widget elementor-widget-icon\" data-id=\"31ad490\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-box-open\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M425.7 256c-16.9 0-32.8-9-41.4-23.4L320 126l-64.2 106.6c-8.7 14.5-24.6 23.5-41.5 23.5-4.5 0-9-.6-13.3-1.9L64 215v178c0 14.7 10 27.5 24.2 31l216.2 54.1c10.2 2.5 20.9 2.5 31 0L551.8 424c14.2-3.6 24.2-16.4 24.2-31V215l-137 39.1c-4.3 1.3-8.8 1.9-13.3 1.9zm212.6-112.2L586.8 41c-3.1-6.2-9.8-9.8-16.7-8.9L320 64l91.7 152.1c3.8 6.3 11.4 9.3 18.5 7.3l197.9-56.5c9.9-2.9 14.7-13.9 10.2-23.1zM53.2 41L1.7 143.8c-4.6 9.2.3 20.2 10.1 23l197.9 56.5c7.1 2 14.7-1 18.5-7.3L320 64 69.8 32.1c-6.9-.8-13.5 2.7-16.6 8.9z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7433d1f elementor-widget elementor-widget-heading\" data-id=\"7433d1f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"#\">All-in-One Solution<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7ae27c7 elementor-widget elementor-widget-heading\" data-id=\"7ae27c7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Create impactful videos tailored for any purpose.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-791aba6\" data-id=\"791aba6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-89c5fe4 elementor-view-stacked drdt-ignore-dark elementor-shape-circle elementor-widget elementor-widget-icon\" data-id=\"89c5fe4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-laptop\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M624 416H381.54c-.74 19.81-14.71 32-32.74 32H288c-18.69 0-33.02-17.47-32.77-32H16c-8.8 0-16 7.2-16 16v16c0 35.2 28.8 64 64 64h512c35.2 0 64-28.8 64-64v-16c0-8.8-7.2-16-16-16zM576 48c0-26.4-21.6-48-48-48H112C85.6 0 64 21.6 64 48v336h512V48zm-64 272H128V64h384v256z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f701a00 elementor-widget elementor-widget-heading\" data-id=\"f701a00\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"#\">Edit Anywhere\n<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-905f9dd elementor-widget elementor-widget-heading\" data-id=\"905f9dd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Create stunning videos anywhere, anytime.\n\n\n\n<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-ee39f60 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-parent\" data-id=\"ee39f60\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d865f3c elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"d865f3c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Explore Our Diverse Character Families<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-53b308c elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"53b308c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tWe offer a wide selection of character families for you to choose from.  You&#8217;ll find the perfect characters to bring your animations to life and captivate your audience.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0915a11 elementor-widget elementor-widget-shortcode\" data-id=\"0915a11\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><div class=\"carousel-slider-outer carousel-slider-outer-image-carousel-url carousel-slider-outer-23882\" style=\"--carousel-slider-nav-color:rgb(255,255,255);--carousel-slider-active-nav-color:#00d1b2;--carousel-slider-arrow-size:48px;--carousel-slider-bullet-size:10px\">\n<div id=\"&#039;id-23882\" class=\"carousel-slider carousel-slider-23882 arrows-visibility-always dots-visibility-never arrows-outside dots-center dots-circle owl-carousel\" data-slide-type=\"image-carousel-url\" data-owl-settings='{\"nav\":true,\"dots\":false,\"slideBy\":1,\"stagePadding\":0,\"margin\":20,\"loop\":true,\"lazyLoad\":false,\"autoplay\":true,\"autoplayTimeout\":4000,\"autoplaySpeed\":500,\"autoplayHoverPause\":true,\"autoWidth\":false,\"responsive\":{\"300\":{\"items\":1},\"576\":{\"items\":2},\"768\":{\"items\":2},\"1024\":{\"items\":3},\"1280\":{\"items\":4},\"1536\":{\"items\":4}}}'>\n<div class=\"carousel-slider__item\">\n\t<a href=\"https:\/\/www.anifuzion.com\/characters\/biz-fam-family\" target=\"_self\"><img decoding=\"async\" alt=\"Biz Fam Character Family\" src=\"https:\/\/www.anifuzion.com\/wp-content\/uploads\/2024\/11\/biz-fam-family-showcase-slide.png\" \/><div class=\"carousel-slider__caption\"><h4 class=\"title\">Biz Fam Character Family<\/h4><\/div><\/a><\/div>\n<div class=\"carousel-slider__item\">\n\t<a href=\"https:\/\/www.anifuzion.com\/characters\/buddies-family\" target=\"_self\"><img decoding=\"async\" alt=\"\" src=\"https:\/\/www.anifuzion.com\/wp-content\/uploads\/2024\/11\/buddies-family-showcase-slide.png\" \/><div class=\"carousel-slider__caption\"><h4 class=\"title\">Buddies Character Family<\/h4><\/div><\/a><\/div>\n<div class=\"carousel-slider__item\">\n\t<a href=\"https:\/\/www.anifuzion.com\/characters\/buddies-vol-1-family\" target=\"_self\"><img decoding=\"async\" alt=\"\" src=\"https:\/\/www.anifuzion.com\/wp-content\/uploads\/2024\/11\/buddies-vol-1-family-showcase-slide.png\" \/><div class=\"carousel-slider__caption\"><h4 class=\"title\">Buddies Vol 1 Character Family<\/h4><\/div><\/a><\/div>\n<div class=\"carousel-slider__item\">\n\t<a href=\"https:\/\/www.anifuzion.com\/characters\/buddies-vol-2-family\" target=\"_self\"><img decoding=\"async\" alt=\"\" src=\"https:\/\/www.anifuzion.com\/wp-content\/uploads\/2024\/11\/buddies-vol-2-family-showcase-slide.png\" \/><div class=\"carousel-slider__caption\"><h4 class=\"title\">Buddies Vol 2 Character Family<\/h4><\/div><\/a><\/div>\n<div class=\"carousel-slider__item\">\n\t<a href=\"https:\/\/www.anifuzion.com\/characters\/clay-family\" target=\"_self\"><img decoding=\"async\" alt=\"\" src=\"https:\/\/www.anifuzion.com\/wp-content\/uploads\/2024\/11\/clay-family-showcase-slide.png\" \/><div class=\"carousel-slider__caption\"><h4 class=\"title\">Clay Character Family<\/h4><\/div><\/a><\/div>\n<div class=\"carousel-slider__item\">\n\t<a href=\"https:\/\/www.anifuzion.com\/characters\/color-crew-family\" target=\"_self\"><img decoding=\"async\" alt=\"\" src=\"https:\/\/www.anifuzion.com\/wp-content\/uploads\/2024\/11\/color-crew-family-showcase-slide.png\" \/><div class=\"carousel-slider__caption\"><h4 class=\"title\">Color Crew Character Family<\/h4><\/div><\/a><\/div>\n<div class=\"carousel-slider__item\">\n\t<a href=\"https:\/\/www.anifuzion.com\/characters\/dream-squad-family\" target=\"_self\"><img decoding=\"async\" alt=\"\" src=\"https:\/\/www.anifuzion.com\/wp-content\/uploads\/2024\/11\/dream-squad-family-slide.png\" \/><div class=\"carousel-slider__caption\"><h4 class=\"title\">Dream Squad Character Family<\/h4><\/div><\/a><\/div>\n<div class=\"carousel-slider__item\">\n\t<a href=\"https:\/\/www.anifuzion.com\/characters\/fantasy-family\" target=\"_self\"><img decoding=\"async\" alt=\"\" src=\"https:\/\/www.anifuzion.com\/wp-content\/uploads\/2024\/11\/fantasy-family-showcase-slide.png\" \/><div class=\"carousel-slider__caption\"><h4 class=\"title\">Fantasy Character Family<\/h4><\/div><\/a><\/div>\n<div class=\"carousel-slider__item\">\n\t<a href=\"https:\/\/www.anifuzion.com\/characters\/jumbloo-family\" target=\"_self\"><img decoding=\"async\" alt=\"\" src=\"https:\/\/www.anifuzion.com\/wp-content\/uploads\/2024\/11\/jumbloo-jumbloo-family-slide.png\" \/><div class=\"carousel-slider__caption\"><h4 class=\"title\">Jumbloo Character Family<\/h4><\/div><\/a><\/div>\n<div class=\"carousel-slider__item\">\n\t<a href=\"https:\/\/www.anifuzion.com\/characters\/low-poly-vol-1-family\" target=\"_self\"><img decoding=\"async\" alt=\"\" src=\"https:\/\/www.anifuzion.com\/wp-content\/uploads\/2024\/11\/low-poly-vol-1-family-slide.png\" \/><div class=\"carousel-slider__caption\"><h4 class=\"title\">Low Poly Vol 1 Character Family<\/h4><\/div><\/a><\/div>\n<div class=\"carousel-slider__item\">\n\t<a href=\"https:\/\/www.anifuzion.com\/characters\/low-poly-vol-2-family\" target=\"_self\"><img decoding=\"async\" alt=\"\" src=\"https:\/\/www.anifuzion.com\/wp-content\/uploads\/2024\/11\/low-poly-vol-2-family-slide.png\" \/><div class=\"carousel-slider__caption\"><h4 class=\"title\">Low Poly Vol 2 Character Family<\/h4><\/div><\/a><\/div>\n<div class=\"carousel-slider__item\">\n\t<a href=\"https:\/\/www.anifuzion.com\/characters\/manga-vol-1-family\" target=\"_self\"><img decoding=\"async\" alt=\"\" src=\"https:\/\/www.anifuzion.com\/wp-content\/uploads\/2024\/11\/manga-vol-1-family-slide.png\" \/><div class=\"carousel-slider__caption\"><h4 class=\"title\">Mango Vol 1 Character Family<\/h4><\/div><\/a><\/div>\n<div class=\"carousel-slider__item\">\n\t<a href=\"https:\/\/www.anifuzion.com\/characters\/manga-vol-2-family\" target=\"_self\"><img decoding=\"async\" alt=\"\" src=\"https:\/\/www.anifuzion.com\/wp-content\/uploads\/2024\/11\/manga-vol-2-family-slide.png\" \/><div class=\"carousel-slider__caption\"><h4 class=\"title\">Mango Vol 2 Character Family<\/h4><\/div><\/a><\/div>\n<div class=\"carousel-slider__item\">\n\t<a href=\"https:\/\/www.anifuzion.com\/characters\/pirate-kit-family\" target=\"_self\"><img decoding=\"async\" alt=\"\" src=\"https:\/\/www.anifuzion.com\/wp-content\/uploads\/2024\/11\/pirate-kit-family-showcase-slide.png\" \/><div class=\"carousel-slider__caption\"><h4 class=\"title\">Pirate Kit Character Family<\/h4><\/div><\/a><\/div>\n<div class=\"carousel-slider__item\">\n\t<a href=\"https:\/\/www.anifuzion.com\/characters\/realistic-family\" target=\"_self\"><img decoding=\"async\" alt=\"\" src=\"https:\/\/www.anifuzion.com\/wp-content\/uploads\/2024\/11\/realistic-family-showcase-slide.png\" \/><div class=\"carousel-slider__caption\"><h4 class=\"title\">Realistic Character Family<\/h4><\/div><\/a><\/div>\n<div class=\"carousel-slider__item\">\n\t<a href=\"https:\/\/www.anifuzion.com\/characters\/street-people-family\" target=\"_self\"><img decoding=\"async\" alt=\"\" src=\"https:\/\/www.anifuzion.com\/wp-content\/uploads\/2024\/11\/street-people-family-slide.png\" \/><div class=\"carousel-slider__caption\"><h4 class=\"title\">Street People Character Family<\/h4><\/div><\/a><\/div>\n<div class=\"carousel-slider__item\">\n\t<a href=\"https:\/\/www.anifuzion.com\/characters\/sushi-clan-family\" target=\"_self\"><img decoding=\"async\" alt=\"\" src=\"https:\/\/www.anifuzion.com\/wp-content\/uploads\/2024\/11\/sushi-clan-family-showcase-slide.png\" \/><div class=\"carousel-slider__caption\"><h4 class=\"title\">Sushi Clan Character Family<\/h4><\/div><\/a><\/div>\n<div class=\"carousel-slider__item\">\n\t<a href=\"https:\/\/www.anifuzion.com\/characters\/toon-vol-1-family\" target=\"_self\"><img decoding=\"async\" alt=\"\" src=\"https:\/\/www.anifuzion.com\/wp-content\/uploads\/2024\/11\/toon-vol-1-family-slide.png\" \/><div class=\"carousel-slider__caption\"><h4 class=\"title\">Toon Vol 1 Character Family<\/h4><\/div><\/a><\/div>\n<div class=\"carousel-slider__item\">\n\t<a href=\"https:\/\/www.anifuzion.com\/characters\/toon-vol-2-family\" target=\"_self\"><img decoding=\"async\" alt=\"\" src=\"https:\/\/www.anifuzion.com\/wp-content\/uploads\/2024\/11\/toon-vol-2-family-slide.png\" \/><div class=\"carousel-slider__caption\"><h4 class=\"title\">Toon Vol 2 Character Family<\/h4><\/div><\/a><\/div>\n<div class=\"carousel-slider__item\">\n\t<a href=\"https:\/\/www.anifuzion.com\/characters\/voxel-family\" target=\"_self\"><img decoding=\"async\" alt=\"\" src=\"https:\/\/www.anifuzion.com\/wp-content\/uploads\/2024\/11\/voxel-family-showcase-slide.png\" \/><div class=\"carousel-slider__caption\"><h4 class=\"title\">Voxel Character Family<\/h4><\/div><\/a><\/div>\n<\/div><!-- .carousel-slider-23882 -->\n<\/div><!-- .carousel-slider-outer-23882 -->\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Meet the Animated Stars of AniFuzion! Step into the world of animation with AniFuzion\u2019s character families! From dynamic 2D to captivating 3D designs, explore a wide range of customizable characters using this powerful online animation tool that will elevate your storytelling. Featured Families Unlock animation magic with AniFuzion, your go-to online animation creator! Design with dynamic 2D and stunning 3D customizable characters to bring your ideas to life. Realistic Family Manga Family Street People Family Low Poly Family Anime and Cartoon Bring Anime and Cartoon characters to life with AniFuzion, your trusted online animation maker! Create vibrant, customizable character families in dynamic 2D and immersive 3D Manga Vol 1 Family Manga Vol 2 Family Jumbloo Family Toon Vol 1 Family Toon Vol 2 Family Pirate Kit Family Sushi Clan Family Chibi Family Adventurer Family Dream Squad Family Sushi Clan Family Chibi Family Low Poly Bring simplicity and style together with AniFuzion\u2019s Low Poly Character Family! As your go-to online animation maker, craft customizable, minimalist characters in dynamic 2D and stunning 3D to enhance your creative projects. Low Poly Vol 1 Family Low Poly Vol 2 Family Voxel Family Low Poly Animal Family Cute and Fun Add charm and playfulness to your animations with AniFuzion\u2019s Cute and Fun Character Family! This online animation tool lets you design delightful, customizable characters in both vibrant 2D and engaging 3D. Clay Family Biz Family Color Crew Family Buddies 1 Family Buddies Vol 2 Family Buddies Vol 1 Family Street People Vol 2 Fantasy and Misc Transform your creative vision with AniFuzion\u2019s Fantasy and Misc Character Family! This online animation maker offers a diverse range of customizable characters in magical 2D and stunning 3D styles. Fantasy Family SpaceKit Family Shade Family Janny Doe, Director Animals Explore endless possibilities with AniFuzion\u2019s Animals Character Family! This online animation tool lets you craft unique, customizable animal characters in lively 2D and realistic 3D formats. Cute Animals Low Poly Animals Shade Family Janny Doe, Director EASY TO USE No More Software Hassles! Unlock your creativity with a click. Discover a variety of features, effects, and templates to bring your vision to life, including dynamic 2D and 3D characters. Easy to Use Effortless simplicity for professional-quality animations. Lightweight Lightweight video creation without the hassle of installation. All-in-One Solution Create impactful videos tailored for any purpose. Edit Anywhere Create stunning videos anywhere, anytime. Explore Our Diverse Character Families We offer a wide selection of character families for you to choose from. You&#8217;ll find the perfect characters to bring your animations to life and captivate your audience.<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"content-type":"","footnotes":""},"class_list":["post-24339","page","type-page","status-publish","hentry","no-post-thumbnail"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Dynamic Character Families | Online Animation Maker - AniFuzion Indonesia<\/title>\n<meta name=\"description\" content=\"Explore AniFuzion&#039;s character families\u20142D, 3D, Low Poly, Anime, Cartoon, and more. Create videos, presentations, and more with customizable characters, no software needed!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.anifuzion.com\/id\/characters\/\" \/>\n<meta property=\"og:locale\" content=\"id_ID\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dynamic Character Families | Online Animation Maker - AniFuzion Indonesia\" \/>\n<meta property=\"og:description\" content=\"Explore AniFuzion&#039;s character families\u20142D, 3D, Low Poly, Anime, Cartoon, and more. Create videos, presentations, and more with customizable characters, no software needed!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.anifuzion.com\/id\/characters\/\" \/>\n<meta property=\"og:site_name\" content=\"AniFuzion Indonesia\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-29T04:15:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/12\/top-screenshot.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimasi waktu membaca\" \/>\n\t<meta name=\"twitter:data1\" content=\"10 menit\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.anifuzion.com\/id\/characters\/\",\"url\":\"https:\/\/www.anifuzion.com\/id\/characters\/\",\"name\":\"Dynamic Character Families | Online Animation Maker - AniFuzion Indonesia\",\"isPartOf\":{\"@id\":\"https:\/\/www.anifuzion.com\/id\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.anifuzion.com\/id\/characters\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.anifuzion.com\/id\/characters\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/12\/top-screenshot.png\",\"datePublished\":\"2024-12-06T06:18:48+00:00\",\"dateModified\":\"2025-05-29T04:15:46+00:00\",\"description\":\"Explore AniFuzion's character families\u20142D, 3D, Low Poly, Anime, Cartoon, and more. Create videos, presentations, and more with customizable characters, no software needed!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.anifuzion.com\/id\/characters\/#breadcrumb\"},\"inLanguage\":\"id\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.anifuzion.com\/id\/characters\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"id\",\"@id\":\"https:\/\/www.anifuzion.com\/id\/characters\/#primaryimage\",\"url\":\"https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/12\/top-screenshot.png\",\"contentUrl\":\"https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/12\/top-screenshot.png\",\"width\":928,\"height\":525},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.anifuzion.com\/id\/characters\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.anifuzion.com\/id\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Character Families\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.anifuzion.com\/id\/#website\",\"url\":\"https:\/\/www.anifuzion.com\/id\/\",\"name\":\"AniFuzion Indonesia\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.anifuzion.com\/id\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"id\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dynamic Character Families | Online Animation Maker - AniFuzion Indonesia","description":"Explore AniFuzion's character families\u20142D, 3D, Low Poly, Anime, Cartoon, and more. Create videos, presentations, and more with customizable characters, no software needed!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.anifuzion.com\/id\/characters\/","og_locale":"id_ID","og_type":"article","og_title":"Dynamic Character Families | Online Animation Maker - AniFuzion Indonesia","og_description":"Explore AniFuzion's character families\u20142D, 3D, Low Poly, Anime, Cartoon, and more. Create videos, presentations, and more with customizable characters, no software needed!","og_url":"https:\/\/www.anifuzion.com\/id\/characters\/","og_site_name":"AniFuzion Indonesia","article_modified_time":"2025-05-29T04:15:46+00:00","og_image":[{"url":"https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/12\/top-screenshot.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Estimasi waktu membaca":"10 menit"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.anifuzion.com\/id\/characters\/","url":"https:\/\/www.anifuzion.com\/id\/characters\/","name":"Dynamic Character Families | Online Animation Maker - AniFuzion Indonesia","isPartOf":{"@id":"https:\/\/www.anifuzion.com\/id\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.anifuzion.com\/id\/characters\/#primaryimage"},"image":{"@id":"https:\/\/www.anifuzion.com\/id\/characters\/#primaryimage"},"thumbnailUrl":"https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/12\/top-screenshot.png","datePublished":"2024-12-06T06:18:48+00:00","dateModified":"2025-05-29T04:15:46+00:00","description":"Explore AniFuzion's character families\u20142D, 3D, Low Poly, Anime, Cartoon, and more. Create videos, presentations, and more with customizable characters, no software needed!","breadcrumb":{"@id":"https:\/\/www.anifuzion.com\/id\/characters\/#breadcrumb"},"inLanguage":"id","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.anifuzion.com\/id\/characters\/"]}]},{"@type":"ImageObject","inLanguage":"id","@id":"https:\/\/www.anifuzion.com\/id\/characters\/#primaryimage","url":"https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/12\/top-screenshot.png","contentUrl":"https:\/\/www.anifuzion.com\/id\/wp-content\/uploads\/sites\/10\/2024\/12\/top-screenshot.png","width":928,"height":525},{"@type":"BreadcrumbList","@id":"https:\/\/www.anifuzion.com\/id\/characters\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.anifuzion.com\/id\/"},{"@type":"ListItem","position":2,"name":"Character Families"}]},{"@type":"WebSite","@id":"https:\/\/www.anifuzion.com\/id\/#website","url":"https:\/\/www.anifuzion.com\/id\/","name":"AniFuzion Indonesia","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.anifuzion.com\/id\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"id"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/www.anifuzion.com\/id\/wp-json\/wp\/v2\/pages\/24339","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.anifuzion.com\/id\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.anifuzion.com\/id\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.anifuzion.com\/id\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.anifuzion.com\/id\/wp-json\/wp\/v2\/comments?post=24339"}],"version-history":[{"count":157,"href":"https:\/\/www.anifuzion.com\/id\/wp-json\/wp\/v2\/pages\/24339\/revisions"}],"predecessor-version":[{"id":29436,"href":"https:\/\/www.anifuzion.com\/id\/wp-json\/wp\/v2\/pages\/24339\/revisions\/29436"}],"wp:attachment":[{"href":"https:\/\/www.anifuzion.com\/id\/wp-json\/wp\/v2\/media?parent=24339"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}